{"id":1173,"date":"2011-10-05T07:46:03","date_gmt":"2011-10-05T05:46:03","guid":{"rendered":"http:\/\/www.loligrub.be\/blog\/?p=1173"},"modified":"2011-10-02T15:13:09","modified_gmt":"2011-10-02T13:13:09","slug":"un-message-sans-qui-ce-site-nexisterait-pas-vs-les-premiers-pas","status":"publish","type":"post","link":"https:\/\/www.loligrub.be\/blog\/2011\/10\/05\/un-message-sans-qui-ce-site-nexisterait-pas-vs-les-premiers-pas\/","title":{"rendered":"Un message sans qui ce site n&rsquo;existerait pas ! vs les premiers pas  &#8230;"},"content":{"rendered":"<p><a href=\"http:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2011\/10\/Torvalds.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-1181\" title=\"Torvalds\" src=\"http:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2011\/10\/Torvalds.jpg\" alt=\"\" width=\"147\" height=\"110\" \/><\/a>20 ans d\u00e9j\u00e0 et pour moi,\u00a0 personnellement, en 1991, une ann\u00e9e remplie de souvenirs : voyage de rh\u00e9tos (URSS), premier pas\u00a0 \u00e0 l&rsquo;universit\u00e9, premier&#8230;\u00a0\u00a0 A l&rsquo;\u00e9poque,\u00a0 j&rsquo;ignorais tout du monde informatique, je n&rsquo;imaginais pas que lors de mes premiers tours \u00e0 la foire de Li\u00e8ge (dite foire d&rsquo;octobre) un email venant du grand nord se r\u00e9pandait via de nombreux serveurs informatiques&#8230;<\/p>\n<p>Cet email nous pouvons le lire sur <a title=\"mail\" href=\"http:\/\/fr.wikisource.org\/wiki\/Naissance_de_Linux#Traduction\">ce site<\/a>\u00a0 mais je le partage avec vous ci-apr\u00e8s\u00a0 :<\/p>\n<pre>De: Linus Benedict Torvalds (torvalds@klaava.Helsinki.FI)\r\nSujet: Sources d'un noyau libre(ou gratuit) de type minix pour 386-AT\r\n\r\nNewsgroups: comp.os.minix\r\nDate: 1991-10-05 08:53:28 PST<\/pre>\n<p><!--more--><\/p>\n<pre> Regrettez vous avec nostalgie le bon vieux temps de minix-1.1,\r\nquand les hommes \u00e9taient des durs et \u00e9crivaient eux-m\u00eame les pilotes\r\npour leur mat\u00e9riel ?  \u00cates vous sans projet int\u00e9ressant et avez vous envie\r\nde mettre les mains dans le cambouis d'un OS que vous pouvez adapter\r\n\u00e0 vos besoins ? Est-ce que \u00e7a vous \u00e9nerve quand tout marche bien\r\nsous minix ?  Ne passez vous plus de nuits blanches \u00e0 essayer de faire\r\nmarcher un super programme ? Alors ce message est s\u00fbrement pour vous.\r\n\r\n Comme je l'ai dit il y a un mois, je travaille en ce moment\r\nsur une version libre (ou gratuite) d'un minix-like pour les machines\r\nde type AT-386. C'en est enfin \u00e0 un stade o\u00f9 il est m\u00eame utilisable\r\n(ou pas, \u00e7a d\u00e9pend de ce que vous voulez), et j'ai envie de distribuer\r\nces sources \u00e0 une plus grande \u00e9chelle. Il en est seulement \u00e0 la version\r\n0.02 (+1 avec d\u00e9j\u00e0 un (tr\u00e8s petit) patch), mais j'ai r\u00e9ussi \u00e0 ex\u00e9cuter\r\nbash\/gcc\/gnu-make\/gnu-sed\/compress etc. avec.\r\n\r\n Les sources de mon projet peuvent \u00eatre trouv\u00e9es \u00e0 nic.funet.fi\r\n(12.214.6.100) dans le r\u00e9pertoire \/pub\/OS\/Linux. Ce r\u00e9pertoire contient\r\naussi un fichier README et quelques binaires pour travailler sous linux\r\n(bash, update et gcc, que demander de plus ?). Les sources compl\u00e8tes du\r\nnoyau sont fournies, car rien du code de minix n'a \u00e9t\u00e9 utilis\u00e9. Les\r\nsources des biblioth\u00e8ques ne sont que partiellement libres, donc elles ne\r\npeuvent pas \u00eatre redistribu\u00e9es pour le moment. Le syst\u00e8me peut \u00eatre\r\ncompil\u00e9 tel quel et est cens\u00e9 fonctionner. Heh.\r\n\r\n Les sources des binaires (bash et gcc) sont situ\u00e9es au m\u00eame endroit,\r\ndans \/pub\/gnu.\r\n\r\n ALERTE! AVERTISSEMENT! NOTE! Ces sources ont tout de m\u00eame besoin de\r\nminix-386 (et gcc-1.40, peut-\u00eatre m\u00eame 1.37.1, je n'ai pas essay\u00e9) pour\r\n\u00eatre compil\u00e9es.\r\n\r\n En plus, vous avez besoin de minix pour le configurer et l'installer si\r\nvous voulez le lancer, donc ce n'est pas encore un syst\u00e8me ind\u00e9pendant.\r\nPour ceux qui n'ont pas minix, j'y travaille. Vous avez aussi besoin\r\nd'\u00eatre un peu bidouilleur pour le configurer, donc ceux qui cherchent une\r\nalternative \u00e0 minix-386, passez votre chemin. Il est pour l'instant\r\ndestin\u00e9 aux bidouilleurs qui sont int\u00e9ress\u00e9s par les syst\u00e8mes\r\nd'exploitation et les 386 qui ont acc\u00e8s \u00e0 minix.\r\n\r\n Le syst\u00e8me a besoin d'un disque dur compatible AT (IDE est parfait) et\r\nEGA\/VGA.\r\n\r\n Si vous \u00eates toujours int\u00e9ress\u00e9, veuillez lire le README\/RELNOTES sur le\r\nftp, et\/ou envoyez moi un mail pour des infos suppl\u00e9mentaires.\r\n\r\n Je vous entends d\u00e9j\u00e0 (enfin, presque) vous demander \"pourquoi?\". Le HURD\r\nva sortir dans un an (ou deux, ou un mois, qui sait), et j'ai d\u00e9j\u00e0 minix.\r\nCeci est un syst\u00e8me pour les bidouilleurs par un bidouilleur. Je me suis\r\nbien amus\u00e9 \u00e0 le faire, et \u00e7a plaira peut-\u00eatre \u00e0 quelqu'un d'y jeter un\r\ncoup d'oeil et m\u00eame de l'adapter \u00e0 ses propres besoins. Il est\r\nsuffisamment petit pour le comprendre, l'utiliser et le modifier, et\r\nj'attends impatiemment les commentaires que vous pourriez y apporter.\r\n\r\n Ca m'int\u00e9resserait aussi de prendre contact avec quelqu'un qui a \u00e9crit\r\nun(e) utilitaire\/biblioth\u00e8que pour minix. Si le fruit de vos efforts est\r\nlibrement redistribuable (sous copyright ou m\u00eame dans le domaine public),\r\nj'aimerais prendre contact avez vous, pour l'ajouter au syst\u00e8me. J'utilise\r\npour l'instant estdio de Earl Chews (merci pour ce syt\u00e8me sympa et\r\nfonctionnel, Earl), et des travaux similaires sont les bienvenus. Vos (C)\r\n(copyrights) seront bien s\u00fbr laiss\u00e9s intacts. Envoyez-moi un message si\r\nvous d\u00e9sirez me laisser utiliser votre code.\r\n\r\n Linus\r\n\r\n PS. \u00e0 PHIL NELSON! Je n'arrive pas \u00e0 vous joindre, et je ne cesse\r\nd'obtenir \"erreur d'envoi - domaine \"strawberry\" (fraise) inconnu\" ou un\r\ntruc dans le genre.<\/pre>\n<p>Vous l&rsquo;avez compris,\u00a0 Linus a donn\u00e9 vie \u00e0 Linux. Le noyau de Linux f\u00eate donc ses 20 ans, c&rsquo;est un adulte maintenant, souhaitons lui un<\/p>\n<p style=\"text-align: center;\">HEUREUX ANNIVERSAIRE et qu&rsquo;il nous apporte plein de bonnes surprises !<\/p>\n<pre><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>20 ans d\u00e9j\u00e0 et pour moi,\u00a0 personnellement, en 1991, une ann\u00e9e remplie de souvenirs : voyage de rh\u00e9tos (URSS), premier pas\u00a0 \u00e0 l&rsquo;universit\u00e9, premier&#8230;\u00a0\u00a0 A l&rsquo;\u00e9poque,\u00a0 j&rsquo;ignorais tout du monde informatique, je n&rsquo;imaginais pas que lors de mes premiers tours &hellip; <a href=\"https:\/\/www.loligrub.be\/blog\/2011\/10\/05\/un-message-sans-qui-ce-site-nexisterait-pas-vs-les-premiers-pas\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[77],"class_list":["post-1173","post","type-post","status-publish","format-standard","hentry","category-news","tag-linux"],"_links":{"self":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/comments?post=1173"}],"version-history":[{"count":8,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/1173\/revisions"}],"predecessor-version":[{"id":1178,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/1173\/revisions\/1178"}],"wp:attachment":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/media?parent=1173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/categories?post=1173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/tags?post=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}