{"id":1870,"date":"2012-03-24T08:16:12","date_gmt":"2012-03-24T07:16:12","guid":{"rendered":"http:\/\/www.loligrub.be\/blog\/?p=1870"},"modified":"2012-03-23T22:14:55","modified_gmt":"2012-03-23T21:14:55","slug":"rssil-a-maubeuge-les-2-et-3-juin-2012","status":"publish","type":"post","link":"https:\/\/www.loligrub.be\/blog\/2012\/03\/24\/rssil-a-maubeuge-les-2-et-3-juin-2012\/","title":{"rendered":"RSSIL \u00e0 Maubeuge les 2 et 3 juin 2012"},"content":{"rendered":"<p><a href=\"http:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2012\/03\/logo_left.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-1961\" title=\"Logo RSSIL 2012\" src=\"http:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2012\/03\/logo_left.png\" alt=\"Logo RSSIL 2012\" width=\"301\" height=\"110\" srcset=\"https:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2012\/03\/logo_left.png 502w, https:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2012\/03\/logo_left-300x109.png 300w\" sizes=\"auto, (max-width: 301px) 100vw, 301px\" \/><\/a>La 7\u00e8me \u00e9dition des RSSIL (<strong>R<\/strong>encontres <strong>S<\/strong>olutions <strong>S<\/strong>\u00e9curit\u00e9 et <strong>I<\/strong>nformatique <strong>L<\/strong>ibre) se d\u00e9roulera \u00e0 Maubeuge samedi 2 et dimanche 3 juin \u00e0 l&rsquo;Espace Sculfort.<\/p>\n<p>Les organisateurs viennent de publier sur le site <a href=\"http:\/\/www.rssil.org\/\" target=\"_blank\">rssil.org<\/a> les premi\u00e8res annonces de conf\u00e9rences et workshops :<\/p>\n<ul>\n<li>\u00ab\u00a0Attaques par complexit\u00e9 et complexit\u00e9 des attaques\u00a0\u00bb, par Robert Erra<\/li>\n<li>\u00a0\u00bb OpenOffice \u00ab\u00a0, avec un atelier tenu par Sylvain Denis, ainsi qu&rsquo;une conf\u00e9rence et un atelier \u00a0\u00bb Logiciels Libres &amp; Bureautique \u00a0\u00bb anim\u00e9s par Antoine Van Elstraete<\/li>\n<\/ul>\n<p>L&rsquo;appel \u00e0 <!--more-->conf\u00e9rence pour 2012 se poursuit, des ateliers d\u00e9monstratifs et techniques seront propos\u00e9s, et un challenge de Ethical Hacking \u00ab\u00a0Hacknowledge\u00a0\u00bb se d\u00e9roulera durant 12 heures.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 7\u00e8me \u00e9dition des RSSIL (Rencontres Solutions S\u00e9curit\u00e9 et Informatique Libre) se d\u00e9roulera \u00e0 Maubeuge samedi 2 et dimanche 3 juin \u00e0 l&rsquo;Espace Sculfort. Les organisateurs viennent de publier sur le site rssil.org les premi\u00e8res annonces de conf\u00e9rences et workshops &hellip; <a href=\"https:\/\/www.loligrub.be\/blog\/2012\/03\/24\/rssil-a-maubeuge-les-2-et-3-juin-2012\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134,1],"tags":[11,15,292,18,293],"class_list":["post-1870","post","type-post","status-publish","format-standard","hentry","category-local","category-news","tag-ateliers","tag-conference","tag-hacking","tag-rssil","tag-securite"],"_links":{"self":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/1870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/comments?post=1870"}],"version-history":[{"count":4,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/1870\/revisions"}],"predecessor-version":[{"id":1963,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/1870\/revisions\/1963"}],"wp:attachment":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/media?parent=1870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/categories?post=1870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/tags?post=1870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}