{"id":298,"date":"2011-06-13T10:45:38","date_gmt":"2011-06-13T08:45:38","guid":{"rendered":"http:\/\/www.loligrub.be\/blog\/?p=298"},"modified":"2011-08-03T20:54:15","modified_gmt":"2011-08-03T18:54:15","slug":"inauguration-du-wolfplex-hackerspace-a-charleroi","status":"publish","type":"post","link":"https:\/\/www.loligrub.be\/blog\/2011\/06\/13\/inauguration-du-wolfplex-hackerspace-a-charleroi\/","title":{"rendered":"Inauguration du Wolfplex Hackerspace \u00e0 Charleroi"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"vertical-align: text-bottom;\" title=\"Wolfplex\" src=\"http:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2011\/06\/Wolfplex-Header-940x150.png\" alt=\"\" width=\"637\" height=\"101\" \/><\/p>\n<p>Au c\u0153ur de la ville de Charleroi, l&rsquo;association <a title=\"http:\/\/www.wolfplex.org\" href=\"http:\/\/www.wolfplex.org\">Wolfplex<\/a> veut cr\u00e9er un ensemble de projets favorisant les contacts entre des personnes souhaitant porter un autre regard sur la soci\u00e9t\u00e9.\u00a0 D\u00e9di\u00e9 au d\u00e9veloppement logiciel, \u00e0 l\u2019\u00e9lectronique, \u00e0 la robotique et aux arts num\u00e9riques, Wolfplex ouvre cet hackerspace, le premier de Wallonie, qui s\u2019adressera \u00e0 toute personne souhaitant accro\u00eetre ses connaissances et transformer ses id\u00e9es en r\u00e9alit\u00e9.<br \/>\n<!--more--><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"border: 1px solid black; margin: 2px 10px;\" title=\"Wolfplex Hackerspace Charleroi\" src=\"http:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2011\/06\/38px-Glider.svg_.png\" alt=\"\" width=\"38\" height=\"38\" \/>L&rsquo;inauguration de cet hackerspace aura lieu du vendredi 24 au lundi 27 juin prochains et repr\u00e9sentera un moment fort pour ces passionn\u00e9s de libert\u00e9.\u00a0 Ils organiseront des ateliers, des conf\u00e9rences, dans une bonne ambiance de hacking<sup style=\"font-size: 10pt;\">1<\/sup>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" style=\"border: 1px solid black; margin-left: 3px; margin-right: 3px;\" title=\"Wolfplex\" src=\"http:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2011\/06\/280px-WolfplexLogo.png\" alt=\"\" width=\"123\" height=\"123\" \/>Les mots \u00ab\u00a0hack\u00a0\u00bb ou \u00ab\u00a0hacker\u00a0\u00bb peuvent vous rappeler quelques grands titres de l&rsquo;information par rapport au piratage informatique qui est un d\u00e9lit, mais ici nous utilisons les mots \u00ab\u00a0hack\u00a0\u00bb et \u00ab\u00a0hacker\u00a0\u00bb pour leur signification anglaise \u00e0 savoir l&rsquo;approfondissement de la connaissance par la recherche et l&rsquo;essai.\u00a0 Alors n&rsquo;ayez crainte, il n&rsquo;y aura rien de d\u00e9lictueux dans cet \u00e9v\u00e9nement.<\/p>\n<p>Si vous souhaitez participer \u00e0 cet \u00e9v\u00e9nement et afin de faciliter la t\u00e2che des<br \/>\norganisateurs, vous pouvez contactez <a title=\"mvanhede@april.org\" href=\"mailto:mvanhede@april.org\">Mathieu Van Hede<\/a> par courriel.<\/p>\n<p>Infos : <a title=\"http:\/\/www.wolfplex.org\" href=\"http:\/\/www.wolfplex.org\">http:\/\/www.wolfplex.org<\/a><\/p>\n<p>[1] Il n&rsquo;est ni simple ni ais\u00e9 d&rsquo;un point de vue \u00e9thique, de pr\u00e9senter sommairement les<br \/>\nmotivations d&rsquo;un hacker, afin d&rsquo;estimer avec justesse et lucidit\u00e9 les cons\u00e9quences de ses<br \/>\nactions.\u00a0 Disons &#8211; de mani\u00e8re g\u00e9n\u00e9rale &#8211; que si la joie de connaissance libre reste un<br \/>\nbienfait (d\u00e9fendu par LoLiGrUB), la volont\u00e9 de nuire \u00e0 son semblable reste une erreur,<br \/>\n\u00e0 jamais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au c\u0153ur de la ville de Charleroi, l&rsquo;association Wolfplex veut cr\u00e9er un ensemble de projets favorisant les contacts entre des personnes souhaitant porter un autre regard sur la soci\u00e9t\u00e9.\u00a0 D\u00e9di\u00e9 au d\u00e9veloppement logiciel, \u00e0 l\u2019\u00e9lectronique, \u00e0 la robotique et aux &hellip; <a href=\"https:\/\/www.loligrub.be\/blog\/2011\/06\/13\/inauguration-du-wolfplex-hackerspace-a-charleroi\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134,1],"tags":[46,45],"class_list":["post-298","post","type-post","status-publish","format-standard","hentry","category-local","category-news","tag-charleroi","tag-hacker"],"_links":{"self":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/comments?post=298"}],"version-history":[{"count":23,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/298\/revisions"}],"predecessor-version":[{"id":812,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/298\/revisions\/812"}],"wp:attachment":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/media?parent=298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/categories?post=298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/tags?post=298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}