{"id":2995,"date":"2014-01-05T17:34:46","date_gmt":"2014-01-05T16:34:46","guid":{"rendered":"http:\/\/www.loligrub.be\/blog\/?p=2995"},"modified":"2014-01-15T23:38:41","modified_gmt":"2014-01-15T22:38:41","slug":"jeudis-du-libre-le-16-janvier-a-mons-un-erp-pour-qui-pourquoi-lopensource-qui-est-openerp","status":"publish","type":"post","link":"https:\/\/www.loligrub.be\/blog\/2014\/01\/05\/jeudis-du-libre-le-16-janvier-a-mons-un-erp-pour-qui-pourquoi-lopensource-qui-est-openerp\/","title":{"rendered":"Jeudis du Libre le 16 janvier \u00e0 Mons : un ERP pour qui ? Pourquoi l\u2019OpenSource ? Qui est OpenERP ?"},"content":{"rendered":"<div>\n<p><a href=\"http:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2014\/01\/logo_openerp.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2996 alignright\" alt=\"Logo OpenERP\" src=\"http:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2014\/01\/logo_openerp-300x111.png\" width=\"300\" height=\"111\" srcset=\"https:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2014\/01\/logo_openerp-300x111.png 300w, https:\/\/www.loligrub.be\/blog\/wp-content\/uploads\/2014\/01\/logo_openerp.png 648w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ce jeudi 16 janvier 2014 \u00e0 19h se d\u00e9roulera la 25\u00e8me s\u00e9ance montoise des <a title=\"http:\/\/jeudisdulibre.be\" href=\"http:\/\/jeudisdulibre.be\" rel=\"nofollow\">Jeudis du Libre de Belgique<\/a>.<\/p>\n<p>Le sujet de cette s\u00e9ance : <strong>un ERP pour qui ? Pourquoi l\u2019OpenSource ? Qui est OpenERP ?<\/strong><\/p>\n<p>Th\u00e9matique : <strong>Progiciel de Gestion Int\u00e9gr\u00e9<\/strong><\/p>\n<p>Public : <strong>Programmeurs|Responsables d&rsquo;entreprise|\u00e9tudiants<\/strong><\/p>\n<p>L&rsquo;animateur conf\u00e9rencier : <strong>S\u00e9bastien Dieu<\/strong> (<a title=\"http:\/\/www.bhc.be\" href=\"http:\/\/www.bhc.be\" rel=\"nofollow\">BHC<\/a>)<\/p>\n<p>Lieu de cette s\u00e9ance : <strong>HEPH Condorcet, Chemin du Champ de Mars, 15 &#8211; 7000 Mons &#8211;\u00a0<\/strong><strong> Salle \u201cSnack\/restaurant\u201d<\/strong> (cf. <a title=\"http:\/\/www.openstreetmap.org\/?mlat=50.46436&amp;mlon=3.95274#map=18\/50.46436\/3.95274\" href=\"http:\/\/www.openstreetmap.org\/?mlat=50.46436&amp;mlon=3.95274#map=18\/50.46436\/3.95274\" rel=\"nofollow\">ce plan<\/a> sur le site d&rsquo;Openstreetmap; ATTENTION, l&rsquo;entr\u00e9e est peu visible de la voie principale, elle se trouve dans l&rsquo;angle form\u00e9 par un tr\u00e8s grand parking).<\/p>\n<p>La participation sera gratuite et ne n\u00e9cessitera que votre<!--more--> inscription nominative, de pr\u00e9f\u00e9rence pr\u00e9alable, ou \u00e0 l&rsquo;entr\u00e9e de la s\u00e9ance. Merci d&rsquo;indiquer votre intention (m\u00eame incertaine) en vous inscrivant via la page <a title=\"http:\/\/jeudisdulibre.fikket.com\/\" href=\"http:\/\/jeudisdulibre.fikket.com\/\" rel=\"nofollow\">http:\/\/jeudisdulibre.fikket.com\/<\/a><\/p>\n<p>Cette s\u00e9ance sera suivie d&rsquo;un verre de l&rsquo;amiti\u00e9, offert par la <em>Cat\u00e9gorie \u00c9conomique<\/em> de la Haute \u00c9cole Condorcet.<\/p>\n<p>Si vous \u00eates int\u00e9ress\u00e9(e) par ce cycle mensuel, n\u2019h\u00e9sitez pas \u00e0 consulter l&rsquo;<a title=\"http:\/\/jeudisdulibre.be\/grille-pour-mons\/\" href=\"http:\/\/jeudisdulibre.be\/grille-pour-mons\/\" rel=\"nofollow\">agenda<\/a> et \u00e0 vous inscrire sur la <a title=\"http:\/\/jeudisdulibre.be\/news\/lists\/?p=subscribe&amp;id=1\" href=\"http:\/\/jeudisdulibre.be\/news\/lists\/?p=subscribe&amp;id=1\" rel=\"nofollow\">liste de diffusion<\/a> afin de recevoir syst\u00e9matiquement les annonces.<\/p>\n<p>Pour rappel, les Jeudis du Libre se veulent des rencontres autour de th\u00e9matiques des Logiciels Libres. Les rencontres montoises se d\u00e9roulent chaque troisi\u00e8me jeudi du mois, et sont organis\u00e9es dans des locaux et en collaboration avec des Hautes \u00c9coles et Facult\u00e9s Universitaires du P\u00f4le Hainuyer d&rsquo;enseignement sup\u00e9rieur impliqu\u00e9es dans les formations d\u2019informaticiens (<a title=\"http:\/\/www.umons.ac.be\/\" href=\"http:\/\/www.umons.ac.be\/\" rel=\"nofollow\">UMONS<\/a>, <a title=\"http:\/\/www.heh.be\/\" href=\"http:\/\/www.heh.be\/\" rel=\"nofollow\">HEH<\/a> et <a title=\"http:\/\/www.condorcet.be\/\" href=\"http:\/\/www.condorcet.be\/\" rel=\"nofollow\">Condorcet<\/a>), et avec le concours de l\u2019A.S.B.L. <a title=\"http:\/\/www.loligrub.be\/\" href=\"http:\/\/www.loligrub.be\/\" rel=\"nofollow\">LoLiGrUB<\/a>, active dans la promotion des logiciels libres.<\/p>\n<p><strong>Description<\/strong> : Qu\u2019est-ce qu\u2019un ERP, ce terme effraye souvent les plus petites structures et pourtant, par son approche modulaire, OpenERP propose des solutions de gestion pour tous types d\u2019entreprises, de l\u2019ind\u00e9pendant \u00e0 la multinationale.<\/p>\n<p>Bas\u00e9 en Wallonie, OpenERP est un logiciel de gestion int\u00e9gr\u00e9 en entreprise. Il comprend une suite compl\u00e8te et \u00e9tendue d&rsquo;applications permettant par exemple de g\u00e9rer les contacts (CRM), ventes, projets, stocks, la comptabilit\u00e9, les ressources humaines, ou encore le processus de production.<\/p>\n<p>L&rsquo;expos\u00e9 abordera successivement :<\/p>\n<ul>\n<li>\n<div>Qui est BHC<\/div>\n<\/li>\n<li>\n<div>L&rsquo;importance d&rsquo;un ERP en entreprise<\/div>\n<\/li>\n<li>\n<div>Qu&rsquo;est ce que l&rsquo;OpenSource<\/div>\n<\/li>\n<li>\n<div>Qui est OpenERP<\/div>\n<\/li>\n<\/ul>\n<p>Finalement, vous pourrez suivre une d\u00e9monstration, assur\u00e9e par Nicolas Doclot, project manager OpenERP, montrant l&rsquo;utilisation de diff\u00e9rents flux classiques dans OpenERP. De la qualification d\u2019un lead \u00e0 la facturation en quelques clics, tout cela avec un impact sur les stocks, les ressources,\u2026<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ce jeudi 16 janvier 2014 \u00e0 19h se d\u00e9roulera la 25\u00e8me s\u00e9ance montoise des Jeudis du Libre de Belgique. Le sujet de cette s\u00e9ance : un ERP pour qui ? Pourquoi l\u2019OpenSource ? Qui est OpenERP ? Th\u00e9matique : Progiciel &hellip; <a href=\"https:\/\/www.loligrub.be\/blog\/2014\/01\/05\/jeudis-du-libre-le-16-janvier-a-mons-un-erp-pour-qui-pourquoi-lopensource-qui-est-openerp\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134,3,1],"tags":[15,192,289],"class_list":["post-2995","post","type-post","status-publish","format-standard","hentry","category-local","category-loligrub","category-news","tag-conference","tag-jeudis-du-libre","tag-openerp"],"_links":{"self":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/2995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/comments?post=2995"}],"version-history":[{"count":5,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/2995\/revisions"}],"predecessor-version":[{"id":3009,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/2995\/revisions\/3009"}],"wp:attachment":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/media?parent=2995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/categories?post=2995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/tags?post=2995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}