{"id":4002,"date":"2025-05-05T18:21:09","date_gmt":"2025-05-05T16:21:09","guid":{"rendered":"https:\/\/www.loligrub.be\/blog\/?p=4002"},"modified":"2025-05-05T18:21:10","modified_gmt":"2025-05-05T16:21:10","slug":"samedi-17-mai-evaluer-developper-et-certifier-ses-competences-numeriques-avec-pix","status":"publish","type":"post","link":"https:\/\/www.loligrub.be\/blog\/2025\/05\/05\/samedi-17-mai-evaluer-developper-et-certifier-ses-competences-numeriques-avec-pix\/","title":{"rendered":"Samedi 17 mai: \u00c9valuer, d\u00e9velopper et certifier ses comp\u00e9tences num\u00e9riques avec Pix"},"content":{"rendered":"\n<p><a href=\"https:\/\/pix.org\/fr\/\">Pix<\/a> est un service accessible sur le web permettant d&rsquo;\u00e9valuer, d\u00e9velopper et certifier gratuitement ses comp\u00e9tences num\u00e9riques ! Il peut se pratiquer au cours de la scolarit\u00e9 d\u00e8s le secondaire, aider les enseignants, formateurs, professionnels de tous secteurs et citoyens \u00e0 se positionner et d\u00e9velopper leur culture num\u00e9rique. Conform\u00e9ment au cadre de r\u00e9f\u00e9rence europ\u00e9en DIGCOMP (Digital Competence Framework for citizens), Pix se base sur les comp\u00e9tences num\u00e9riques dont l\u2019apprentissage est utile tout au long de la vie, regroup\u00e9es en 5 domaines. Leur certification se divise principalement en 6 niveaux de ma\u00eetrise.<\/p>\n\n\n\n\n\n<p>La pr\u00e9sentation de l&rsquo;outil lors de l&rsquo;atelier sera accompagn\u00e9e d&rsquo;une d\u00e9monstration, et vous serez encourag\u00e9s \u00e0 tester Pix par vous-m\u00eame. N&rsquo;oubliez pas de vous munir d&rsquo;un PC ou d&rsquo;une tablette (il suffit de disposer d&rsquo;un navigateur web) !<\/p>\n<p>Bien entendu, l\u2019atelier traitera comme toujours les aides, questions et r\u00e9ponses pour des installations et configurations de logiciels libres. Et notre atelier suivant du 21 juin sera consacr\u00e9 au logiciel Kodi, comme Media Center.<\/p>\n<p>Comme d\u2019habitude, la s\u00e9ance d\u00e9butera \u00e0 15h dans les locaux du CAJ-MIR. L\u2019adresse : All\u00e9e de la Motte num\u00e9ro 4 \u00e0 Boussu.<\/p>\n<p><strong>Et soyez attentif \u00e0 notre site web, car nous pr\u00e9voyons aussi d&rsquo;organiser un repas convivial (en pr\u00e9paration) !<\/strong><\/p>\n<p>Venez nombreux. Bonne ambiance assur\u00e9e !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pix est un service accessible sur le web permettant d&rsquo;\u00e9valuer, d\u00e9velopper et certifier gratuitement ses comp\u00e9tences num\u00e9riques ! Il peut se pratiquer au cours de la scolarit\u00e9 d\u00e8s le secondaire, aider les enseignants, formateurs, professionnels de tous secteurs et citoyens &hellip; <a href=\"https:\/\/www.loligrub.be\/blog\/2025\/05\/05\/samedi-17-mai-evaluer-developper-et-certifier-ses-competences-numeriques-avec-pix\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134,3,1],"tags":[11],"class_list":["post-4002","post","type-post","status-publish","format-standard","hentry","category-local","category-loligrub","category-news","tag-ateliers"],"_links":{"self":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/4002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/comments?post=4002"}],"version-history":[{"count":2,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/4002\/revisions"}],"predecessor-version":[{"id":4004,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/4002\/revisions\/4004"}],"wp:attachment":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/media?parent=4002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/categories?post=4002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/tags?post=4002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}