{"id":4028,"date":"2026-02-10T22:14:58","date_gmt":"2026-02-10T21:14:58","guid":{"rendered":"https:\/\/www.loligrub.be\/blog\/?p=4028"},"modified":"2026-02-10T22:14:59","modified_gmt":"2026-02-10T21:14:59","slug":"samedi-21-fevrier-un-nouveau-pc-sans-casser-sa-tirelire","status":"publish","type":"post","link":"https:\/\/www.loligrub.be\/blog\/2026\/02\/10\/samedi-21-fevrier-un-nouveau-pc-sans-casser-sa-tirelire\/","title":{"rendered":"Samedi 21 f\u00e9vrier : un nouveau PC sans casser sa tirelire"},"content":{"rendered":"\n<p>Samedi 21 f\u00e9vrier \u00e0 15h, notre atelier sera consacr\u00e9 aux moyens de surmonter des difficult\u00e9s fr\u00e9quemment rencontr\u00e9es : la migration impossible de Windows 10 \u00e0 Windows 11, la flamb\u00e9e des prix des m\u00e9moires et SSD rendant prohibitif l&rsquo;achat d&rsquo;un nouvel ordinateur, que faire d&rsquo;un PC de r\u00e9cup\u00e9ration qui n&rsquo;a pourtant pas encore 10 ans,\u2026<\/p>\n\n\n\n<p>Toute ces situations sont autant d&rsquo;occasion de franchir un cap et de passer \u00e0 une distribution GNU\/Linux, moins exigeante que Windows, moderne, s\u00fbre et respectueuse des donn\u00e9es priv\u00e9es. Pour vous-m\u00eame, ou pour un proche ! Les discussions, questions et r\u00e9ponses lors de l&rsquo;atelier permettront d&rsquo;envisager des solutions \u00e0 co\u00fbt nul ou r\u00e9duit.<\/p>\n\n\n\n<p>Notre atelier comme les suivants comprendra aussi un temps consacr\u00e9 au Raspberry Pi. Ce 21 f\u00e9vrier, nous aborderons son utilisation comme serveur vid\u00e9o, en y incluant la fa\u00e7on d&rsquo;y connecter une PiCam (module de cam\u00e9ra sp\u00e9cialement con\u00e7u pour les Raspberry Pi).<\/p>\n\n\n\n<p>Bien entendu, l\u2019atelier traitera comme toujours les aides, questions et r\u00e9ponses pour des installations et configurations de logiciels libres.<\/p>\n\n\n\n<p>En ce d\u00e9but d&rsquo;ann\u00e9e, nous rappelons \u00e9galement aux membres adh\u00e9rents et effectifs de l\u2019ASBL l\u2019importance de vous acquitter de la cotisation annuelle (cf. la page \u00ab Nous rejoindre \u00bb). Merci d\u2019avance !<\/p>\n\n\n\n<p>Comme d\u2019habitude, l\u2019atelier d\u00e9butera \u00e0 15h dans les locaux du CAJ-MIR. L\u2019adresse : All\u00e9e de la Motte num\u00e9ro 4 \u00e0 Boussu.<\/p>\n\n\n\n<p>Venez nombreux. Bonne ambiance assur\u00e9e !<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Samedi 21 f\u00e9vrier \u00e0 15h, notre atelier sera consacr\u00e9 aux moyens de surmonter des difficult\u00e9s fr\u00e9quemment rencontr\u00e9es : la migration impossible de Windows 10 \u00e0 Windows 11, la flamb\u00e9e des prix des m\u00e9moires et SSD rendant prohibitif l&rsquo;achat d&rsquo;un nouvel &hellip; <a href=\"https:\/\/www.loligrub.be\/blog\/2026\/02\/10\/samedi-21-fevrier-un-nouveau-pc-sans-casser-sa-tirelire\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[77,325],"class_list":["post-4028","post","type-post","status-publish","format-standard","hentry","category-loligrub","tag-linux","tag-raspberry-pi"],"_links":{"self":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/4028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/comments?post=4028"}],"version-history":[{"count":1,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/4028\/revisions"}],"predecessor-version":[{"id":4029,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/posts\/4028\/revisions\/4029"}],"wp:attachment":[{"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/media?parent=4028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/categories?post=4028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loligrub.be\/blog\/wp-json\/wp\/v2\/tags?post=4028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}